{"id":7436,"count":1,"description":"","link":"https:\/\/tomchun.tw\/tomchun\/tag\/%e3%80%8a%e5%af%b6%e5%8f%af%e5%a4%a2-%e6%9c%b1-%e7%b4%ab%e3%80%8b%e9%9f%93%e5%9c%8bpokemon-winter-festa%e6%b4%bb%e5%8b%95%e6%88%9f%e8%84%8a%e9%be%8d%e5%ba%8f%e8%99%9f\/","name":"\u300a\u5bf6\u53ef\u5922 \u6731 \/ \u7d2b\u300b\u97d3\u570bPokemon Winter Festa\u6d3b\u52d5\u621f\u810a\u9f8d\u5e8f\u865f","slug":"%e3%80%8a%e5%af%b6%e5%8f%af%e5%a4%a2-%e6%9c%b1-%e7%b4%ab%e3%80%8b%e9%9f%93%e5%9c%8bpokemon-winter-festa%e6%b4%bb%e5%8b%95%e6%88%9f%e8%84%8a%e9%be%8d%e5%ba%8f%e8%99%9f","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tomchun.tw\/tomchun\/wp-json\/wp\/v2\/tags\/7436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomchun.tw\/tomchun\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tomchun.tw\/tomchun\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tomchun.tw\/tomchun\/wp-json\/wp\/v2\/posts?tags=7436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}